{"id":142,"date":"2023-04-14T21:03:08","date_gmt":"2023-04-14T21:03:08","guid":{"rendered":"https:\/\/recetasdelmar.com\/?page_id=142"},"modified":"2024-04-01T11:39:41","modified_gmt":"2024-04-01T11:39:41","slug":"bacalao","status":"publish","type":"page","link":"https:\/\/recetasdelmar.com\/index.php\/bacalao\/","title":{"rendered":"bacalao"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"background-color:#2a2c6b;padding-top:6vw;padding-right:6vw;padding-bottom:6vw;padding-left:6vw\">\n<div class=\"wp-block-group alignwide is-vertical is-nowrap is-layout-flex wp-container-core-group-layout-1 wp-block-group-is-layout-flex\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.38%\">\n<p class=\"has-base-color has-text-color has-large-font-size\" style=\"font-style:normal;font-weight:700\">empanada de bacalao<\/p>\n\n\n\n<p class=\"has-base-color has-text-color\" style=\"font-style:normal;font-weight:700\">receta de m\u00f3nica prego @pandebroa<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-base-color has-text-color has-medium-font-size\" style=\"font-style:normal;font-weight:700\">ingredientes<\/h2>\n\n\n\n<p class=\"has-base-color has-text-color\">Para la masa:<\/p>\n\n\n\n<ul class=\"has-base-color has-text-color\">\n<li>400 g de harina panadera<\/li>\n\n\n\n<li>200-230 g de agua&nbsp;<\/li>\n\n\n\n<li>5 g de levadura fresca&nbsp;<\/li>\n\n\n\n<li>1 cucharadita de sal<\/li>\n\n\n\n<li>40 ml de aceite del relleno para gramar la masa<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-base-color has-text-color is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33%\">\n<div style=\"height:2vw\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"732\" src=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7515-1024x732.jpg\" alt=\"\" class=\"wp-image-400\" srcset=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7515-1024x732.jpg 1024w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7515-300x214.jpg 300w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7515-768x549.jpg 768w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7515.jpg 1048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"732\" src=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7566-1024x732.jpg\" alt=\"\" class=\"wp-image-407\" srcset=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7566-1024x732.jpg 1024w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7566-300x214.jpg 300w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7566-768x549.jpg 768w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7566.jpg 1048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide has-base-color has-text-color is-layout-flex wp-container-core-columns-layout-2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:69%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"732\" src=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7553-1024x732.jpg\" alt=\"\" class=\"wp-image-406\" srcset=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7553-1024x732.jpg 1024w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7553-300x214.jpg 300w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7553-768x549.jpg 768w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2023\/10\/MOK_7553.jpg 1048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Comenzamos haciendo la masa, para ello echamos el agua en un bol amplio y a\u00f1adimos la levadura fresca. La disolvemos y volcamos la harina. La trabajamos con las manos un minuto hasta que est\u00e9 integrada y la dejamos reposar tapada a modo de autolisis.&nbsp;<\/p>\n\n\n\n<p>Para el relleno pelamos y cortamos las cebollas bien finas y pelamos y cortamos un tomate. Lo echamos todo junto en una olla y le a\u00f1adimos el aceite, 1 hoja de laurel 1 cucharadita de piment\u00f3n dulce y sal. Acercamos la olla al fuego y dejamos que se vaya pochando la cebolla durante 1 hora u hora y media a fuego muy suave. Cuando la cebolla est\u00e9 bien pochadita la apartamos del fuego y la dejamos atemperar.<\/p>\n\n\n\n<p>Continuamos con la masa, a la que a\u00f1adiremos 1 cucharadita de sal y un poco de agua y la trabajamos con las manos hasta que est\u00e9 lisa y el\u00e1stica. La colocamos en un bol y la dejamos fermentar tapada hasta que doble su volumen.&nbsp; <\/p>\n\n\n\n<p>A continuaci\u00f3n, preparamos el bacalao, que tendremos descongelado; Le retiramos la piel, revisamos que no tenga espinas y lo troceamos menudo. Lo escurrimos bien y lo reservamos en un bol.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33%\">\n<p>Encendemos el horno a 220\u00baC con calor arriba y abajo y forramos una bandeja con papel del horno. A continuaci\u00f3n, gramaremos la masa y para ello le a\u00f1adimos una cucharada de aceite del relleno y la trabajamos unos minutos. Una vez que la masa est\u00e1 lista, la dividimos en dos, estiramos una parte con la forma del molde y la colocamos encima del papel, que habremos pincelado con aceite del relleno.<\/p>\n\n\n\n<p>Escurrimos bien el aceite de la cebolla pochada y la extendemos bien repartida por la superficie de la masa que tenemos en la bandeja. Encima le colocamos el bacalao, que tendremos troceado, en crudo y el pimiento morr\u00f3n asado y troceado.&nbsp;<\/p>\n\n\n\n<p>Ya con el relleno colocado, estiramos la masa restante y cubrimos la empanada con ella, que nos quede del tama\u00f1o del molde. Hacemos un agujero en medio y el repulgue para sellarla. La decoramos con los restos de masa que nos queden y finalmente la pincelamos con aceite del relleno.&nbsp; La horneamos a 220\u00baC durante 40 minutos. Pasado el tiempo, verificamos que est\u00e1 cocida, la retiramos del horno, la dejamos atemperar y ya la tenemos lista.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"EMPANADA DE BACALAO RECETA TRADICIONAL GALLEGA DE MONICA PREGO @pandebroa.by.monikaprego75 | RECETAS DE PESCADO\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/eBYML51ToHI?start=264&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-center has-base-background-color has-background\"><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-center has-large-font-size\" style=\"font-style:normal;font-weight:700\">bu\u00f1uelos de bacalao facil\u00edsimos<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<p class=\"has-small-font-size\">Prep\u00e1rate para disfrutar de un aperitivo que seguramente se convertir\u00e1 en uno de tus favoritos. Los bu\u00f1uelos de bacalao son una receta perfecta para un aperitivo de cualquier ocasi\u00f3n o para acompa\u00f1ar de una ensalada en tus cenas del d\u00eda d\u00eda. Atr\u00e9vete a probar esta receta f\u00e1cil y deliciosa de bu\u00f1uelos de bacalao crujientes y doraditos por dentro y esponjosos y tiernos por dentro<\/p>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"732\" src=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-25-1024x732.jpg\" alt=\"\" class=\"wp-image-518 size-full\" srcset=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-25-1024x732.jpg 1024w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-25-300x214.jpg 300w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-25-768x549.jpg 768w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-25-1536x1097.jpg 1536w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-25-2048x1463.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-text-color has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"color:#314d74;margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--30);padding-right:var(--wp--preset--spacing--30);padding-bottom:100px;padding-left:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-jetpack-layout-grid column1-desktop-grid__span-6 column1-desktop-grid__start-2 column1-desktop-grid__row-1 column2-desktop-grid__span-3 column2-desktop-grid__start-9 column2-desktop-grid__row-1 column1-tablet-grid__span-5 column1-tablet-grid__row-1 column2-tablet-grid__span-2 column2-tablet-grid__start-7 column2-tablet-grid__row-1 column1-mobile-grid__span-4 column1-mobile-grid__row-1 column2-mobile-grid__span-4 column2-mobile-grid__row-2 wp-block-jetpack-layout-gutter__nowrap\">\n<div class=\"wp-block-jetpack-layout-grid-column wp-block-jetpack-layout-grid__padding-none\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1786\" src=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-6.jpg\" alt=\"\" class=\"wp-image-511\" srcset=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-6.jpg 2500w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-6-300x214.jpg 300w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-6-1024x732.jpg 1024w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-6-768x549.jpg 768w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-6-1536x1097.jpg 1536w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-6-2048x1463.jpg 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><\/figure>\n\n\n\n<p>Para realizar esta receta, es necesario descongelar el lomo de bacalao la noche anterior. Comenzamos lavando y picando finamente un diente de ajo y un manojo de perejil. Despu\u00e9s, cortamos el bacalao descongelado en trozos peque\u00f1os y lo colocamos en un recipiente a parte.<\/p>\n\n\n\n<p>Con todos los ingredientes ya pesados y listos, procedemos a hacer la masa de los bu\u00f1uelos. En un recipiente grande, batimos dos huevos y salpimentamos, agregamos 100 ml de caldo de pescado y 100 ml de leche. Luego, tamizamos 100 g de harina con una cucharadita de levadura en polvo y se la agregamos a la mezcla anterior. Mezclamos bien para eliminar cualquier grumo que pueda quedar, por \u00faltimo incorporamos el perejil, el y el bacalao .<\/p>\n\n\n\n<p>Dejamos que la masa repose unos 30 minutos y pasado el tiempo vamos friendo los bu\u00f1uelos.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-jetpack-layout-grid-column wp-block-jetpack-layout-grid__padding-none\">\n<p class=\"has-text-color has-medium-font-size\" style=\"color:#385582;font-style:normal;font-weight:700;line-height:1\">ingredientes<\/p>\n\n\n\n<div style=\"height:3px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul>\n<li>1 lomo de bacalao fresco descongelado (300g)<\/li>\n\n\n\n<li>1 manojo de perejil&nbsp;<\/li>\n\n\n\n<li>1 ajo<\/li>\n\n\n\n<li>2 huevos<\/li>\n\n\n\n<li>100 g de harina<\/li>\n\n\n\n<li>Sal<\/li>\n\n\n\n<li>Pimienta&nbsp;<\/li>\n\n\n\n<li>1 cucharadita de levadura en polvo(tipo royal)<\/li>\n\n\n\n<li>Caldo de pescado o agua&nbsp;<\/li>\n\n\n\n<li>leche<\/li>\n\n\n\n<li>Abundante aceite de oliva para fre\u00edr<\/li>\n<\/ul>\n\n\n\n<p>Calentamos abundante aceite de oliva en una sart\u00e9n y una vez haya alcanzado la temperatura \u00f3ptima para fre\u00edr, vamos cogiendo cucharadas de masa y las echamos con cuidado en el aceite.&nbsp;<\/p>\n\n\n\n<p>Continuamos friendo los bu\u00f1uelos de la misma forma hasta que hayamos terminado toda la masa.&nbsp; Una vez que est\u00e9n listos, los servimos para disfrutarlos bien calientes.<\/p>\n\n\n\n<div style=\"height:3px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-center has-base-background-color has-background\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"732\" src=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-13-1024x732.jpg\" alt=\"\" class=\"wp-image-514 size-full\" srcset=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-13-1024x732.jpg 1024w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-13-300x214.jpg 300w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-13-768x549.jpg 768w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-13-1536x1097.jpg 1536w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/sin-titulo-13-2048x1463.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\" style=\"margin-top:0;margin-bottom:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<p class=\"has-extra-small-font-size\">La masa de o bu\u00f1uelos se parece mucho a la de las croquetas pero para esta no necesitaremos bechamel ni la rebozaremos.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-base-color has-text-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"background-color:#3fc5e6;padding-top:100px;padding-bottom:100px\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-layout-3 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h2 class=\"wp-block-heading has-base-color has-text-color\" style=\"margin-top:0px;font-size:clamp(22.544px, 1.409rem + ((1vw - 3.2px) * 1.643), 37px);line-height:1.2\"><strong><strong>bacalao al pil pil con alcaparras<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"has-medium-font-size\"><strong>ingredientes<\/strong><\/p>\n\n\n\n<ul>\n<li>200 g Coliflor<\/li>\n\n\n\n<li>Un chorrito de Nata para cocinar<\/li>\n\n\n\n<li>Un chorro de Leche<\/li>\n\n\n\n<li>Nuez moscada<\/li>\n\n\n\n<li>Sal<\/li>\n\n\n\n<li>Aceite<\/li>\n\n\n\n<li>Bolsa de horno o una hoja de papel aluminio<\/li>\n\n\n\n<li>1-2 Lomos de bacalao Cigalmar<\/li>\n\n\n\n<li>Aceite de oliva<\/li>\n\n\n\n<li>Sa<\/li>\n\n\n\n<li>Alcaparras<\/li>\n<\/ul>\n\n\n\n<ul>\n<li>Aceite de oliva<\/li>\n<\/ul>\n\n\n\n<p>Lo primero que hacemos es preparar el horno a 180\u00ba para que vaya calentando. Una vez hecho esto, vamos a hacer el pur\u00e9 de coliflor. Lavamos la coliflor y desechamos las hojas exteriores, cortamos y cocemos en agua con sal. Una vez lista preparamos el pur\u00e9. Llevamos la coliflor y el resto de ingredientes a una batidora y batimos hasta que tengamos un pur\u00e9 sin grumos.<\/p>\n\n\n\n<p>Ahora es el momento de preparar el bacalao para llevarlo al horno. En el caso de usar bolsa, metemos el lomo y los dem\u00e1s ingredientes en ella, cerramos y colocamos 15 minutos en el horno. <\/p>\n\n\n\n<p>Si lo que usamos es papel albal, vamos a tomar la hoja, colocaremos el lomo de bacalao en el medio de la hoja y vamos a envolver el lomo con el papel de aluminio dejando una abertura arriba para a\u00f1adir los ingredientes. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"BACALAO al PIL PIL facil y rapido \u2764\ufe0f 1 min [Recetas de pescado]\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/NPWsAnoUzKc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Bacalao al pil pil f\u00e1cil y r\u00e1pido 1 min | Cigalmar<\/figcaption><\/figure>\n\n\n\n<p>Una vez a\u00f1adidos todos los ingredientes, cerramos y metemos en el horno quince minutos. Reservaremos el l\u00edquido de la cocci\u00f3n para hacer el pil pil.<\/p>\n\n\n\n<p>Transcurridos los quince minutos, sacamos el pescado del horno y cogemos el l\u00edquido de la cocci\u00f3n, lo ponemos al fuego y lo ligamos con un colador o con una cuchara hasta que quede un poco espeso reservamos hasta servir.<\/p>\n\n\n\n<p>La \u00faltima elaboraci\u00f3n es muy sencilla, ponemos aceite de oliva calentar a fuego muy alto, cuando coja temperatura, a\u00f1adimos las alcaparras, dejamos que se doren, retiramos y reservamos.<\/p>\n\n\n\n<p>En un plato colocamos una cama con el pur\u00e9 de coliflor, encima colocamos el bacalao y la salsa al pil pil y las alcaparras.<\/p>\n\n\n\n<p><strong>Chef<\/strong>: Mateo de Miguel Blanco Mart\u00ed Instagram @mateobaldayo                                             Profesora y coordinadora de cocina: Beatriz Sotelo Instagram @beatrizsotelo<\/p>\n\n\n\n<p><strong>Grabaciones: <\/strong>Malaherba producci\u00f3ns @malaherbaproduccions                                            Claudia Berro Instagram @claudia_berro                                                                               Montaje y sonido: Marta Insua Instagram @insua14<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignwide is-style-default has-base-color has-text-color has-background has-small-font-size is-layout-flow wp-block-group-is-layout-flow\" style=\"background-color:#314d74;padding-top:63px;padding-right:63px;padding-bottom:63px;padding-left:63px\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-layout-4 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<p class=\"has-large-font-size\"><strong>croquetas de bacalao<\/strong><\/p>\n\n\n\n<p>Para la bechamel:<\/p>\n\n\n\n<ul>\n<li>Bacalao fresco descongelado<\/li>\n\n\n\n<li>1 hoja de laurel<\/li>\n\n\n\n<li>50 g de mantequilla o aceite de oliva suave<\/li>\n\n\n\n<li>\u00bd cebolla cortada fina<\/li>\n\n\n\n<li>Una cucharilla de perejil picado<\/li>\n\n\n\n<li>100 g de harina de uso com\u00fan<\/li>\n\n\n\n<li>200 ml de caldo de cocci\u00f3n del bacalao<\/li>\n\n\n\n<li>500 ml de leche entera<\/li>\n\n\n\n<li>Sal<\/li>\n\n\n\n<li>Nuez moscada<\/li>\n<\/ul>\n\n\n\n<p>Para el rebozado:<\/p>\n\n\n\n<ul>\n<li>Pan rallado<\/li>\n\n\n\n<li>2 huevos<\/li>\n\n\n\n<li>Aceite de oliva suave para fre\u00edr<\/li>\n<\/ul>\n\n\n\n<p>Pasamos la croqueta por huevo batido y a continuaci\u00f3n por pan rallado. Con las manos, le vamos dando forma y las colocamos encima de una tabla para que el rebozado se seque un poco.<\/p>\n\n\n\n<p>Las vamos haciendo todas de la misma manera hasta que terminamos la masa. A continuaci\u00f3n, toca fre\u00edrlas.<\/p>\n\n\n\n<p>Ponemos abundante aceite en un cazo o sart\u00e9n y cuando el aceite est\u00e1 caliente las vamos echando una a una, y sin a\u00f1adir muchas juntas. De esta manera evitaremos que el aceite se enfr\u00ede y se abran. Cuando est\u00e9n doradas les damos la vuelta, dejamos que se cocinen por el otro lado y las retiramos para un plato forrado con papel de cocina. Las vamos friendo todas de la misma manera hasta tenerlas todas listas y las servimos calientes.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-background-color has-text-color is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"732\" src=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/DSC_1747-1024x732.jpg\" alt=\"\" class=\"wp-image-528\" srcset=\"https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/DSC_1747-1024x732.jpg 1024w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/DSC_1747-300x214.jpg 300w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/DSC_1747-768x549.jpg 768w, https:\/\/recetasdelmar.com\/wp-content\/uploads\/2024\/02\/DSC_1747.jpg 1048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Preparaci\u00f3n:<\/p>\n\n\n\n<p>Preparamos y pesamos todos los ingredientes de la receta. En una olla ponemos abundante agua a hervir con 1 hoja de laurel y cuando rompa a hervir, echamos el bacalao fresco ya descongelado. Lo dejamos hervir 5 minutos, apagamos el fuego y escurrimos los trozos de bacalao para un recipiente, para que enfr\u00eden un poco.\u00a0<\/p>\n\n\n\n<p>Picamos la cebolla y el perejil bien finitos y los reservamos. A continuaci\u00f3n, desmenuzamos el bacalao y lo dejamos en un recipiente y a su vez, colamos 200 ml de caldo de cocci\u00f3n del bacalao, que usaremos en la bechamel. En una sart\u00e9n calentamos 50 g de mantequilla o aceite de oliva y pochamos la cebolla picada y el perejil. Cuando est\u00e9n transparente, a\u00f1adimos 100 g de harina de golpe y la removemos para que se impregne bien con la mantequilla. Dejamos que se tueste varios minutos y vamos a\u00f1adiendo el caldo que tendremos caliente poco a poco. Tenemos que removerlo r\u00e1pido para que se forme un engrudo o roux, y de esta manera evitaremos que se formen grumos.\u00a0<\/p>\n\n\n\n<p>Sin dejar de remover la bechamel, seguimos a\u00f1adiendo el caldo y a continuaci\u00f3n la leche. Cocemos la bechamel durante unos 10 minutos y cuando est\u00e9 lista le a\u00f1adimos el bacalao desmenuzado. Le rallamos nuez moscada al gusto y sal.&nbsp;<\/p>\n\n\n\n<p>Ponemos la masa de las croquetas en un bol con un poco de agua y la dejamos enfriar tapada hasta el d\u00eda siguiente que formaremos las croquetas.&nbsp;<\/p>\n\n\n\n<p>Al dia siguiente vamos a formar y a rebosar las croquetas. Para ello en un bol batimos dos huevos y en un bol aparte echamos el pan rallado. Con una cuchara cogemos porciones de masa y le vamos dando forma.<\/p>\n\n\n\n<p>*TRUCO: Si no las queremos fre\u00edr todas juntas, las podemos congelar.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-text-color has-background has-link-color wp-elements-caa25b87fd1ccee4968a2d4a651db171 has-global-padding is-layout-constrained wp-container-core-group-layout-8 wp-block-group-is-layout-constrained\" style=\"color:#2a2623;background-color:#f2fffe;margin-top:0px;margin-bottom:0px;padding-top:7vw;padding-bottom:7vw\">\n<div class=\"wp-block-columns alignwide has-text-color is-layout-flex wp-container-core-columns-layout-5 wp-block-columns-is-layout-flex\" style=\"color:#1f4c88\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Bacalao a la Portuguesa | Receta F\u00e1cil!\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/y0e3019ed9Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><strong>Bacalao a la portuguesa receta f\u00e1cil <\/strong>| Cocina con Carmen<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Bacalao a la marinera || RECETA F\u00c1CIL\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/6D-5fpNZNlM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><strong>Bacalao a la marinera Receta f\u00e1cil<\/strong> | La cocina de casa<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Bacalao con Tomate f\u00e1cil y delicioso\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/TNjGDWUjEg8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><strong>Bacalao con tomate f\u00e1cil <\/strong>| La cocina de Carmen<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"BACALAO \ud83d\udc1ffresco con \ud83e\udd90 MARISCO (langostinos, gambas o gambones), Listo en 30 minutos.\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/tFI-pJSartw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><strong>Bacalao fresco con marisco listo en 30 minutos<\/strong> | La cocina de la abuela<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\ud83d\udc1fBacalao en salsa con langostinos \ud83c\udf64 RECETA SEMANA SANTA\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/kej4iG-TmtI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><strong>Bacalao en salsa con langostinos Receta semana santa<\/strong> | La dulce Teresa<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Bacalao a la Cazuela de Tonio Cocina\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ZQOXaLB5Paw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><strong>Bacalao a la cazuela de Tonio Cocina<\/strong> | La cocina del pirata<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"TORTILLITAS de BACALAO \u00a1Incre\u00edbles y adictivas!\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/rmLAOsRQibw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><strong>Tortillas de bacalao incre\u00edbles y adictivas <\/strong>| Y hoy que comemos <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"C\u00f3mo hacer bacalao a la gallega, al estilo de Mariaje\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/xhOICGgGs58?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><strong>C\u00f3mo hacer bacalao a la gallega<\/strong> | La cocina practica y sana de Mariaje<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Brandada de bacalao - Karlos Argui\u00f1ano en tu cocina\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/1E2xGtbC85E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><strong>Brandada de bacalao Karlos Argui\u00f1ano en tu cocina<\/strong> | Hogarman\u00eda<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>empanada de bacalao receta de m\u00f3nica prego @pandebroa ingredientes Para la masa: Comenzamos haciendo la masa, para ello echamos el agua en un bol amplio y a\u00f1adimos la levadura fresca. La disolvemos y volcamos la harina. La trabajamos con las manos un minuto hasta que est\u00e9 integrada y la dejamos reposar tapada a modo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/recetasdelmar.com\/index.php\/wp-json\/wp\/v2\/pages\/142"}],"collection":[{"href":"https:\/\/recetasdelmar.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/recetasdelmar.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/recetasdelmar.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recetasdelmar.com\/index.php\/wp-json\/wp\/v2\/comments?post=142"}],"version-history":[{"count":24,"href":"https:\/\/recetasdelmar.com\/index.php\/wp-json\/wp\/v2\/pages\/142\/revisions"}],"predecessor-version":[{"id":529,"href":"https:\/\/recetasdelmar.com\/index.php\/wp-json\/wp\/v2\/pages\/142\/revisions\/529"}],"wp:attachment":[{"href":"https:\/\/recetasdelmar.com\/index.php\/wp-json\/wp\/v2\/media?parent=142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}